{"id":13079,"date":"2023-10-26T21:07:27","date_gmt":"2023-10-26T21:07:27","guid":{"rendered":"http:\/\/teatinos.org\/?p=13079"},"modified":"2023-10-26T21:07:27","modified_gmt":"2023-10-26T21:07:27","slug":"bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv","status":"publish","type":"post","link":"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/","title":{"rendered":"Bienheureux Paul Burali &#8211; \u00c9v\u00eaque de Plaisance. Archev\u00eaque de Naples. Cardinal. &#8211; IV"},"content":{"rendered":"<p><em><strong>S. Andrew Avellino, premier biographe du bienheureux Paul Burali<\/strong><\/em><\/p>\n<p><strong>R\u00e9forme du culte et de la d\u00e9votion \u00e0 l&rsquo;Eucharistie<\/strong><\/p>\n<p>Arriv\u00e9 \u00e0 Plaisance, il constata que le tabernacle \u00e9tait peu honor\u00e9 et que le Tr\u00e8s Saint Sacrement ne faisait l&rsquo;objet d&rsquo;aucune r\u00e9v\u00e9rence. Il voulut donner l&rsquo;exemple et enseigner au peuple le culte de l&rsquo;Eucharistie, il se levait t\u00f4t le matin et, les yeux baiss\u00e9s, il s&rsquo;agenouillait pendant plusieurs heures devant le Tr\u00e8s Saint Sacrement.<br \/>\nLes fruits ne manquent pas. Le peuple et les nobles, voyant l&rsquo;\u00e9v\u00eaque s&rsquo;agenouiller, apprirent tous \u00e0 s&rsquo;agenouiller et \u00e0 r\u00e9v\u00e9rer le Saint Sacrement. Le bon pr\u00e9lat avait pu faire tant de choses sans dire un mot.<br \/>\nIl vit aussi que tr\u00e8s peu de chanoines se rendaient au ch\u0153ur pour faire la pri\u00e8re du matin. Il ne dit rien. Il commen\u00e7a par s&rsquo;y rendre lui-m\u00eame tous les matins. Ainsi, par son exemple, sans rien imposer, il incita tous les chanoines \u00e0 l&rsquo;office du matin. Ils avaient l&rsquo;habitude de rentrer tr\u00e8s tard. Mais avec lui, ils ont appris \u00e0 \u00eatre tr\u00e8s ponctuels. C&rsquo;est ainsi que, par son exemple, il a r\u00e9form\u00e9 le culte divin sans m\u00e2cher ses mots.<\/p>\n<p>&#8212;&#8212;<br \/>\n<strong>Pri\u00e8re<\/strong><\/p>\n<p>\u00d4 Dieu, qui as manifest\u00e9 dans le bienheureux Paul Burali les voies multiples et admirables de ton appel \u00e0 la perfection chr\u00e9tienne, accorde-nous le r\u00e9confort de sa protection c\u00e9leste pour te suivre de tout notre c\u0153ur. Par le Christ notre Seigneur. Amen.<\/p>\n<p>(il y a un petit silence pour demander la gr\u00e2ce que chacun porte dans son c\u0153ur)<\/p>\n<p>Notre P\u00e8re, Je vous salue Marie et Gloire \u00e0 Dieu<\/p>\n<p>&#8212;&#8212;<br \/>\n<strong>Pens\u00e9e du bienheureux Paul Burali :<\/strong><\/p>\n<p><em>\u00ab\u00a0La mort est douce pour celui qui, par la cons\u00e9cration \u00e0 Dieu, tend vers le ciel. Il est crucifi\u00e9 au monde et le monde est crucifi\u00e9 pour lui, parce que, m\u00e9prisant les richesses humaines, il recherche les r\u00e9alit\u00e9s du ciel, et que, n\u00e9gligeant les volupt\u00e9s du corps, il imite la vie des anges par la chastet\u00e9\u00a0\u00bb.<\/em><\/p>\n<p><strong>QPRD<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S. Andrew Avellino, premier biographe du bienheureux Paul Burali R\u00e9forme du culte et de la d\u00e9votion \u00e0 l&rsquo;Eucharistie Arriv\u00e9 \u00e0 Plaisance, il constata que le tabernacle \u00e9tait peu honor\u00e9 et que le Tr\u00e8s Saint Sacrement ne faisait l&rsquo;objet d&rsquo;aucune r\u00e9v\u00e9rence. Il voulut donner l&rsquo;exemple et enseigner au peuple le culte\u2026<\/p>\n","protected":false},"author":5,"featured_media":13069,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[96],"tags":[],"class_list":["post-13079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bienheureux Paul Burali - \u00c9v\u00eaque de Plaisance. Archev\u00eaque de Naples. Cardinal. - IV - Teatinos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bienheureux Paul Burali - \u00c9v\u00eaque de Plaisance. Archev\u00eaque de Naples. Cardinal. - IV - Teatinos\" \/>\n<meta property=\"og:description\" content=\"S. Andrew Avellino, premier biographe du bienheureux Paul Burali R\u00e9forme du culte et de la d\u00e9votion \u00e0 l&rsquo;Eucharistie Arriv\u00e9 \u00e0 Plaisance, il constata que le tabernacle \u00e9tait peu honor\u00e9 et que le Tr\u00e8s Saint Sacrement ne faisait l&rsquo;objet d&rsquo;aucune r\u00e9v\u00e9rence. Il voulut donner l&rsquo;exemple et enseigner au peuple le culte\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/\" \/>\n<meta property=\"og:site_name\" content=\"Teatinos\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-26T21:07:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/teatinos.org\/wp-content\/uploads\/2023\/10\/Teatinos-en-Camino-Beato-Pablo-Burali-octubre-2023.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Community Manager\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Community Manager\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/\",\"url\":\"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/\",\"name\":\"Bienheureux Paul Burali - \u00c9v\u00eaque de Plaisance. Archev\u00eaque de Naples. Cardinal. - IV - Teatinos\",\"isPartOf\":{\"@id\":\"https:\/\/teatinos.org\/pt-br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/teatinos.org\/wp-content\/uploads\/2023\/10\/Teatinos-en-Camino-Beato-Pablo-Burali-octubre-2023.png\",\"datePublished\":\"2023-10-26T21:07:27+00:00\",\"dateModified\":\"2023-10-26T21:07:27+00:00\",\"author\":{\"@id\":\"https:\/\/teatinos.org\/pt-br\/#\/schema\/person\/10193cb8ac6f163661033cf7ce9006a5\"},\"breadcrumb\":{\"@id\":\"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/#primaryimage\",\"url\":\"https:\/\/teatinos.org\/wp-content\/uploads\/2023\/10\/Teatinos-en-Camino-Beato-Pablo-Burali-octubre-2023.png\",\"contentUrl\":\"https:\/\/teatinos.org\/wp-content\/uploads\/2023\/10\/Teatinos-en-Camino-Beato-Pablo-Burali-octubre-2023.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/teatinos.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bienheureux Paul Burali &#8211; \u00c9v\u00eaque de Plaisance. Archev\u00eaque de Naples. Cardinal. &#8211; IV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/teatinos.org\/pt-br\/#website\",\"url\":\"https:\/\/teatinos.org\/pt-br\/\",\"name\":\"Teatinos\",\"description\":\"Orden de Cl\u00e9rigos Regulares\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/teatinos.org\/pt-br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/teatinos.org\/pt-br\/#\/schema\/person\/10193cb8ac6f163661033cf7ce9006a5\",\"name\":\"Community Manager\",\"url\":\"https:\/\/teatinos.org\/fr\/author\/pascual\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bienheureux Paul Burali - \u00c9v\u00eaque de Plaisance. Archev\u00eaque de Naples. Cardinal. - IV - Teatinos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/","og_locale":"fr_FR","og_type":"article","og_title":"Bienheureux Paul Burali - \u00c9v\u00eaque de Plaisance. Archev\u00eaque de Naples. Cardinal. - IV - Teatinos","og_description":"S. Andrew Avellino, premier biographe du bienheureux Paul Burali R\u00e9forme du culte et de la d\u00e9votion \u00e0 l&rsquo;Eucharistie Arriv\u00e9 \u00e0 Plaisance, il constata que le tabernacle \u00e9tait peu honor\u00e9 et que le Tr\u00e8s Saint Sacrement ne faisait l&rsquo;objet d&rsquo;aucune r\u00e9v\u00e9rence. Il voulut donner l&rsquo;exemple et enseigner au peuple le culte\u2026","og_url":"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/","og_site_name":"Teatinos","article_published_time":"2023-10-26T21:07:27+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/teatinos.org\/wp-content\/uploads\/2023\/10\/Teatinos-en-Camino-Beato-Pablo-Burali-octubre-2023.png","type":"image\/png"}],"author":"Community Manager","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Community Manager","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/","url":"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/","name":"Bienheureux Paul Burali - \u00c9v\u00eaque de Plaisance. Archev\u00eaque de Naples. Cardinal. - IV - Teatinos","isPartOf":{"@id":"https:\/\/teatinos.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/#primaryimage"},"image":{"@id":"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/#primaryimage"},"thumbnailUrl":"https:\/\/teatinos.org\/wp-content\/uploads\/2023\/10\/Teatinos-en-Camino-Beato-Pablo-Burali-octubre-2023.png","datePublished":"2023-10-26T21:07:27+00:00","dateModified":"2023-10-26T21:07:27+00:00","author":{"@id":"https:\/\/teatinos.org\/pt-br\/#\/schema\/person\/10193cb8ac6f163661033cf7ce9006a5"},"breadcrumb":{"@id":"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/#primaryimage","url":"https:\/\/teatinos.org\/wp-content\/uploads\/2023\/10\/Teatinos-en-Camino-Beato-Pablo-Burali-octubre-2023.png","contentUrl":"https:\/\/teatinos.org\/wp-content\/uploads\/2023\/10\/Teatinos-en-Camino-Beato-Pablo-Burali-octubre-2023.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/teatinos.org\/fr\/bienheureux-paul-burali-eveque-de-plaisance-archeveque-de-naples-cardinal-iv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/teatinos.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Bienheureux Paul Burali &#8211; \u00c9v\u00eaque de Plaisance. Archev\u00eaque de Naples. Cardinal. &#8211; IV"}]},{"@type":"WebSite","@id":"https:\/\/teatinos.org\/pt-br\/#website","url":"https:\/\/teatinos.org\/pt-br\/","name":"Teatinos","description":"Orden de Cl\u00e9rigos Regulares","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teatinos.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/teatinos.org\/pt-br\/#\/schema\/person\/10193cb8ac6f163661033cf7ce9006a5","name":"Community Manager","url":"https:\/\/teatinos.org\/fr\/author\/pascual\/"}]}},"rttpg_featured_image_url":{"full":["https:\/\/teatinos.org\/wp-content\/uploads\/2023\/10\/Teatinos-en-Camino-Beato-Pablo-Burali-octubre-2023.png",1080,1080,false],"landscape":["https:\/\/teatinos.org\/wp-content\/uploads\/2023\/10\/Teatinos-en-Camino-Beato-Pablo-Burali-octubre-2023.png",1080,1080,false],"portraits":["https:\/\/teatinos.org\/wp-content\/uploads\/2023\/10\/Teatinos-en-Camino-Beato-Pablo-Burali-octubre-2023.png",1080,1080,false],"thumbnail":["https:\/\/teatinos.org\/wp-content\/uploads\/2023\/10\/Teatinos-en-Camino-Beato-Pablo-Burali-octubre-2023-150x150.png",150,150,true],"medium":["https:\/\/teatinos.org\/wp-content\/uploads\/2023\/10\/Teatinos-en-Camino-Beato-Pablo-Burali-octubre-2023-300x300.png",300,300,true],"large":["https:\/\/teatinos.org\/wp-content\/uploads\/2023\/10\/Teatinos-en-Camino-Beato-Pablo-Burali-octubre-2023-1024x1024.png",1000,1000,true],"1536x1536":["https:\/\/teatinos.org\/wp-content\/uploads\/2023\/10\/Teatinos-en-Camino-Beato-Pablo-Burali-octubre-2023.png",1080,1080,false],"2048x2048":["https:\/\/teatinos.org\/wp-content\/uploads\/2023\/10\/Teatinos-en-Camino-Beato-Pablo-Burali-octubre-2023.png",1080,1080,false]},"rttpg_author":{"display_name":"Community Manager","author_link":"https:\/\/teatinos.org\/fr\/author\/pascual\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/teatinos.org\/fr\/category\/actualite\/\" rel=\"category tag\">Actualit\u00e9<\/a>","rttpg_excerpt":"S. Andrew Avellino, premier biographe du bienheureux Paul Burali R\u00e9forme du culte et de la d\u00e9votion \u00e0 l&rsquo;Eucharistie Arriv\u00e9 \u00e0 Plaisance, il constata que le tabernacle \u00e9tait peu honor\u00e9 et que le Tr\u00e8s Saint Sacrement ne faisait l&rsquo;objet d&rsquo;aucune r\u00e9v\u00e9rence. Il voulut donner l&rsquo;exemple et enseigner au peuple le culte\u2026","_links":{"self":[{"href":"https:\/\/teatinos.org\/fr\/wp-json\/wp\/v2\/posts\/13079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teatinos.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teatinos.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teatinos.org\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/teatinos.org\/fr\/wp-json\/wp\/v2\/comments?post=13079"}],"version-history":[{"count":1,"href":"https:\/\/teatinos.org\/fr\/wp-json\/wp\/v2\/posts\/13079\/revisions"}],"predecessor-version":[{"id":13080,"href":"https:\/\/teatinos.org\/fr\/wp-json\/wp\/v2\/posts\/13079\/revisions\/13080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teatinos.org\/fr\/wp-json\/wp\/v2\/media\/13069"}],"wp:attachment":[{"href":"https:\/\/teatinos.org\/fr\/wp-json\/wp\/v2\/media?parent=13079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teatinos.org\/fr\/wp-json\/wp\/v2\/categories?post=13079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teatinos.org\/fr\/wp-json\/wp\/v2\/tags?post=13079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}